{"id":617,"count":1,"description":"","link":"https:\/\/www.delhitempotravellers.com\/blog\/tag\/durga-puja-in-delhi","name":"durga puja in delhi","slug":"durga-puja-in-delhi","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.delhitempotravellers.com\/blog\/wp-json\/wp\/v2\/tags\/617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.delhitempotravellers.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.delhitempotravellers.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.delhitempotravellers.com\/blog\/wp-json\/wp\/v2\/posts?tags=617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}