{"id":619,"count":1,"description":"","link":"https:\/\/www.delhitempotravellers.com\/blog\/tag\/festival-in-india","name":"festival in india","slug":"festival-in-india","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.delhitempotravellers.com\/blog\/wp-json\/wp\/v2\/tags\/619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.delhitempotravellers.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.delhitempotravellers.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.delhitempotravellers.com\/blog\/wp-json\/wp\/v2\/posts?tags=619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}